{"id":1423,"date":"2023-03-23T07:00:00","date_gmt":"2023-03-23T10:00:00","guid":{"rendered":"http:\/\/nacao.digital\/blog\/?p=1423"},"modified":"2026-06-23T12:16:01","modified_gmt":"2026-06-23T15:16:01","slug":"eventos-de-e-commerce-e-marketing","status":"publish","type":"post","link":"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/","title":{"rendered":"23 eventos de e-commerce e marketing para 2023\/24"},"content":{"rendered":"<p class=\"last-modified\"> <b> <i> Este conte\u00fado foi atualizado em: 23\/06\/2026 <\/i> <\/b> <\/p>\n<p>Participar de eventos de e-commerce e marketing digital \u00e9 uma excelente forma de descobrir tend\u00eancias, ideias inovadoras e detalhes de estrat\u00e9gias bem sucedidas. Al\u00e9m de serem inspiradores e, muitas vezes, decisivos para mudan\u00e7as na gest\u00e3o e nos processos de trabalho, s\u00e3o boas oportunidades para fazer neg\u00f3cios \u2014 o famigerado <em>networking<\/em>.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Da contrata\u00e7\u00e3o de servi\u00e7os e descobertas de ferramentas aos contatos com potenciais fornecedores e clientes, o fato \u00e9 que muitas s\u00e3o as vantagens de participar desses encontros. Por isso, que tal organizar sua agenda 2023 e se programar para participar de uma das 23 dicas que trouxemos neste texto?<\/p>\n\n\n\n<p>Grande parte das sugest\u00f5es oferece trilhas de palestras segmentadas pelas \u00e1reas de atua\u00e7\u00e3o mais comuns: conte\u00fado, atendimento, performance, SEO, vendas e gest\u00e3o. J\u00e1 os principais eventos de e-commerce s\u00e3o focados em plataformas, ferramentas, gest\u00e3o de neg\u00f3cios, inova\u00e7\u00e3o, experi\u00eancia do cliente e empreendedorismo.&nbsp;<\/p>\n\n\n\n<p>As op\u00e7\u00f5es se dividem entre nacionais e internacionais. Escolha a perfeita para o seu nicho e eleve seus conhecimentos!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/nacao.digital\/fale-conosco\/?utm_source=blog&amp;utm_medium=post&amp;utm_content=guia-live-commerce&amp;utm_campaign=eventos-de-e-commerce\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"700\" height=\"100\" src=\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2021\/02\/live-commerce-com-vender-transmissoes-ao-vivo.jpg\" alt=\"live-commerce-com-vender-transmissoes-ao-vivo\" class=\"wp-image-6497\" srcset=\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2021\/02\/live-commerce-com-vender-transmissoes-ao-vivo.jpg 700w, https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2021\/02\/live-commerce-com-vender-transmissoes-ao-vivo-300x43.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Eventos de e-commerce e marketing internacionais<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>1. NRF Retail\u2019s Big Show<\/strong><\/h3>\n\n\n\n<p>Com foco no <a href=\"https:\/\/nacao.digital\/blog\/crise-no-varejo-digital\/\" target=\"_blank\" rel=\"noreferrer noopener\">varejo<\/a>, o <a href=\"https:\/\/nrfbigshow.nrf.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>NRF Retail\u2019s Big Show<\/strong><\/a> \u00e9 o evento mais importante do nicho no mundo, dispondo de conte\u00fados para quem tem neg\u00f3cios tanto online quanto offline. A edi\u00e7\u00e3o de 2023 j\u00e1 aconteceu, mas voc\u00ea j\u00e1 pode come\u00e7ar a se programar para a de 2024.\u00a0<\/p>\n\n\n\n<p>Normalmente, o p\u00fablico se divide entre varejistas, fornecedores e especialistas do setor. Patrocinada por grandes empresas, como Amazon, Microsoft, American Express, Lenovo e Shopify, a feira traz programas de <em>networking<\/em> e conte\u00fado robusto, com abordagem dos principais t\u00f3picos do varejo e previs\u00f5es para os pr\u00f3ximos anos.&nbsp;<\/p>\n\n\n\n<p>A exposi\u00e7\u00e3o costuma contar com um laborat\u00f3rio voltado para a inova\u00e7\u00e3o, apresentando as novidades mais recentes da transforma\u00e7\u00e3o tecnol\u00f3gica para os varejistas.&nbsp;<\/p>\n\n\n\n<p>Confira alguns palestrantes da edi\u00e7\u00e3o 2023: Dylan Bruntil \u2014 Global Director of Retail Technology da New Balance; Pierre Chambe \u2014 Director, Consolidation &amp; Reporting da Sephora; Marina Chernyak \u2014 VP, US Retail da Visa; e Robert DeVito \u2014 Global Director, Chrome Customer and Partner Engineering da Google; Roberto Funari \u2014 CEO da Alpargatas (Havaianas &amp; Rothy&#8217;s), entre muitos outros grandes nomes.<\/p>\n\n\n\n<p>O grande show do varejo \u00e9 o lugar certo para fazer parcerias, transformar neg\u00f3cios e obter <em>insights <\/em>e inspira\u00e7\u00f5es para alavancar o sucesso da sua <a href=\"https:\/\/nacao.digital\/blog\/porque-o-nome-da-sua-empresa-e-essencial-para-o-seu-sucesso\/\" target=\"_blank\" rel=\"noreferrer noopener\">empresa<\/a>.<\/p>\n\n\n\n<ul><li><strong>Quando:<\/strong> 14 a 16 de janeiro de 2024<\/li><li><strong>Onde: <\/strong>Nova York (EUA)<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2. B2B Expo &amp; Conference Berlin Expo<\/strong><\/h3>\n\n\n\n<p>Em 2024, a feira voltada para provedores de servi\u00e7os de e-commerce B2B <a href=\"https:\/\/ecommerceberlin.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>E-commerce Berlin Expo<\/strong><\/a> ganha sua 8\u00aa edi\u00e7\u00e3o, ap\u00f3s encontros de sucesso entre 2016-2023, tendo se estabelecido como um dos principais eventos de com\u00e9rcio eletr\u00f4nico da Alemanha.<\/p>\n\n\n\n<p>Com mais de 27.000 visitantes e 600 expositores, o evento j\u00e1 recebeu empresas not\u00e1veis, como Google, Samsung, Alibaba, Zalando, Facebook, DHL, L&#8217;Oreal, BMW, Adidas, Amazon, Allegro, ING e profissionais de outras empresas de renome j\u00e1 palestraram no encontro.<\/p>\n\n\n\n<ul><li><a href=\"https:\/\/nacao.digital\/blog\/category\/e-commerce\/e-commerce-b2b\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Conte\u00fados para gest\u00e3o de e-commerce B2B? Acesse aqui!<\/strong><\/a><\/li><\/ul>\n\n\n\n<ul><li><strong>Quando: <\/strong>22 de fevereiro de 2024<\/li><li><strong>Onde: <\/strong>Berlim (Alemanha)<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3. Digital Food &amp; Beverage<\/strong><\/h3>\n\n\n\n<p>A <a href=\"https:\/\/foodandbeverageeu.wbresearch.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Digital Food &amp; Beverage<\/strong><\/a> \u00e9 uma confer\u00eancia que re\u00fane heads de <a href=\"https:\/\/nacao.digital\/blog\/plataforma-de-e-commerce\/\" target=\"_blank\" rel=\"noreferrer noopener\">e-commerces<\/a> das marcas e dos varejistas de alimentos e bebidas mais inovadores da Europa. Os participantes ter\u00e3o a oportunidade de obter <em>insights <\/em>sobre vendas, <a href=\"https:\/\/nacao.digital\/blog\/seth-goldin-atendimento-ao-consumidor\/\" target=\"_blank\" rel=\"noreferrer noopener\">atendimento ao cliente<\/a>, modelos de neg\u00f3cios e novas tecnologias para o setor.<\/p>\n\n\n\n<p>Na \u00faltima edi\u00e7\u00e3o do evento, em mar\u00e7o de 2023, foram mais de 400 l\u00edderes de e-commerce, <a href=\"https:\/\/nacao.digital\/blog\/podcasts-de-marketing-digital\/\" target=\"_blank\" rel=\"noreferrer noopener\">marketing digital<\/a> e transforma\u00e7\u00e3o, 50 palestrantes, 40 sess\u00f5es interativas, <em>showroom<\/em> e mais de 8 horas de <em>networking<\/em>.<\/p>\n\n\n\n<p>Profissionais de marcas como Heineken, General Mills, Danone e Kellog compartilham seus conhecimentos com o p\u00fablico durante dois dias de compartilhamento de conhecimento.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2018\/05\/eventos-de-ecommerce.png\" alt=\"A programa\u00e7\u00e3o de 2024 ainda n\u00e3o foi divulgada, mas o evento j\u00e1 tem data e local agendados!\" class=\"wp-image-8048\" width=\"600\" srcset=\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2018\/05\/eventos-de-ecommerce.png 450w, https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2018\/05\/eventos-de-ecommerce-300x200.png 300w, https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2018\/05\/eventos-de-ecommerce-150x100.png 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><figcaption>A programa\u00e7\u00e3o de 2024 ainda n\u00e3o foi divulgada, mas o evento j\u00e1 tem data e local agendados!<\/figcaption><\/figure><\/div>\n\n\n\n<ul><li><strong>Quando: <\/strong>12 a 13 mar\u00e7o de 2024<\/li><li><strong>Onde:<\/strong> Londres (Inglaterra)<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4. Adobe Summit<\/strong><\/h3>\n\n\n\n<p>Mais de 3 mil l\u00edderes de neg\u00f3cios, varejistas, desenvolvedores e ag\u00eancias se conectam para uma confer\u00eancia sobre com\u00e9rcio. O <a href=\"https:\/\/summit.adobe.com\/na\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Adobe Summit<\/strong><\/a> \u00e9 um evento completo e que, ap\u00f3s ter ocorrido na modalidade virtuale em decorr\u00eancia da covid-19, admitiu os dois modelos, o digital e o presencial.<\/p>\n\n\n\n<p>O presencial ocorre em Las Vegas, enquanto que o virtual \u00e9 gratuito e as palestras s\u00e3o disponibilizadas ap\u00f3s o evento. A ideia \u00e9 ajudar profissionais a expandir o conjunto de habilidades que possuem, despertar inspira\u00e7\u00e3o e construir conex\u00f5es que capacitem a transformar a economia digital em uma miss\u00e3o pessoal.<\/p>\n\n\n\n<p>A edi\u00e7\u00e3o de 2023 trouxe palestrantes de diversas \u00e1reas, como <a href=\"https:\/\/nacao.digital\/blog\/marketing-de-conteudo-para-industria\/\" target=\"_blank\" rel=\"noreferrer noopener\">marketing de conte\u00fado<\/a>, <a href=\"https:\/\/nacao.digital\/blog\/commerces-b2b\/\" target=\"_blank\" rel=\"noreferrer noopener\">ci\u00eancia de dados<\/a>, desenvolvimento de sistemas, <a href=\"https:\/\/nacao.digital\/blog\/web-design\/\" target=\"_blank\" rel=\"noreferrer noopener\">web design<\/a> e muito mais, al\u00e9m de executivos.<\/p>\n\n\n\n<p>No total, foram 11 trilhas dispon\u00edveis:<\/p>\n\n\n\n<ul><li>Analytics para jornadas do cliente<\/li><li>Marketing B2B<\/li><li>Gest\u00e3o Colaborativa do Trabalho<\/li><li>Com\u00e9rcio Personalizado<\/li><li>Cadeia de suprimentos de conte\u00fado<\/li><li>Conte\u00fado que Impulsiona o Desempenho<\/li><li>Gerenciamento e ativa\u00e7\u00e3o de dados do cliente<\/li><li>Ecossistema do Desenvolvedor<\/li><li>Envolvimento Omnicanal Personalizado<\/li><li>Potencializando seu neg\u00f3cio digital com a Adobe Experience Cloud<\/li><li>Tend\u00eancias e inspira\u00e7\u00e3o<\/li><\/ul>\n\n\n\n<p>Como a edi\u00e7\u00e3o de 2023 j\u00e1 aconteceu, agora \u00e9 ficar de olho na p\u00e1gina oficial do Adobe Summit e aguardar pela programa\u00e7\u00e3o de 2024!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5. MWC Barcelona \u2013 Mobile World Congress<\/strong><\/h3>\n\n\n\n<p>\u00c9 a maior exposi\u00e7\u00e3o global para a ind\u00fastria mobile, tendo foco na conectividade. O <a href=\"https:\/\/www.mwcbarcelona.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>MWC Barcelona<\/strong><\/a> \u00e9 frequentado por executivos das maiores operadoras m\u00f3veis do mundo, fabricantes de dispositivos, provedores de tecnologia, fornecedores e autores de conte\u00fados.\u00a0<\/p>\n\n\n\n<p>A edi\u00e7\u00e3o de 2023 j\u00e1 aconteceu e os palestrantes trabalharam temas como <a href=\"https:\/\/nacao.digital\/blog\/impactos-do-5g-no-brasil\/\" target=\"_blank\" rel=\"noreferrer noopener\">5G<\/a>, intelig\u00eancia artificial, identidade\/autentica\u00e7\u00e3o digital, empreendedorismo, fintech, ecossistemas de inova\u00e7\u00e3o, infraestrutura de rede e <a href=\"https:\/\/nacao.digital\/blog\/recommerce\/\" target=\"_blank\" rel=\"noreferrer noopener\">sustentabilidade<\/a>.<\/p>\n\n\n\n<p>Enquanto a data oficial da pr\u00f3xima edi\u00e7\u00e3o do evento n\u00e3o sai, d\u00e1 uma olhadinha em como foi a de 2023:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"wpex-responsive-media\"><iframe title=\"MWC Barcelona 2023 - Full Event Highlights\" width=\"980\" height=\"551\" src=\"https:\/\/www.youtube.com\/embed\/MRuVGG-Q4oM?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/span>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>6. Eventos Shoptalk<\/strong><\/h3>\n\n\n\n<p>Desde 2015, cerca de 8 mil varejistas se re\u00fanem em Las Vegas todos os anos para criar o futuro do varejo. O <a href=\"https:\/\/shoptalk.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Shoptalk<\/strong><\/a> se transformou em refer\u00eancia em tecnologia, tend\u00eancias e modelos de neg\u00f3cios para o setor.<\/p>\n\n\n\n<p>Os formatos do evento s\u00e3o variados e envolvem desde mesas-redondas, jantares com curadoria, reuni\u00f5es, estudos de casos, experi\u00eancias visuais imersivas e debates r\u00e1pidos. Ao decorrer de cada ano, s\u00e3o quatro encontros com focos distintos:&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Shoptalk US<\/strong><\/h4>\n\n\n\n<p>A agenda do <a href=\"https:\/\/shoptalk.com\/us\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Shoptalk<\/strong><\/a><strong> <\/strong>abrange as mais recentes tecnologias, tend\u00eancias e modelos de neg\u00f3cios, assim como aborda a r\u00e1pida transforma\u00e7\u00e3o a respeito do que os consumidores descobrem e compram, desde roupas e eletr\u00f4nicos at\u00e9 produtos de <a href=\"https:\/\/nacao.digital\/blog\/quintal-dermocosmeticos\/\" target=\"_blank\" rel=\"noreferrer noopener\">beleza<\/a> e mercearia.<\/p>\n\n\n\n<ul><li><strong>Quando: <\/strong>26 a 29 de mar\u00e7o de 2023<\/li><li><strong>Onde:<\/strong> Mandalay Bay, Las Vegas<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Shoptalk Europe<\/strong><\/h4>\n\n\n\n<p>J\u00e1 o <a href=\"https:\/\/shoptalkeurope.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Shoptalk Europe<\/strong><\/a> re\u00fane varejo e mercado. S\u00e3o mais de 3.500 tomadores de decis\u00e3o dos maiores varejistas e marcas do mundo, startups, empresas de tecnologia, investidores, operadores imobili\u00e1rios, m\u00eddia, analistas e muito mais.<\/p>\n\n\n\n<ul><li><strong>Quando: <\/strong>9 a 11 de maio de 2023<\/li><li><strong>Onde:<\/strong> Barcelona<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Shoptalk Meetup for Women&nbsp;<\/strong><\/h4>\n\n\n\n<p>Voltado para o p\u00fablico feminino do varejo, o <a href=\"https:\/\/shoptalkwomen.retailmeetup.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Shoptalk Meetup for Women<\/strong><\/a> \u00e9 um programa de reuni\u00f5es online com mulheres durante tr\u00eas dias para oferecer oportunidades de networking, visando desenvolver conex\u00f5es significativas por meio de encontros e discuss\u00f5es em pequenos grupos, sejam elas pessoais ou profissionais.<\/p>\n\n\n\n<ul><li><strong>Quando: <\/strong>27 a 29 de junho de 2023<\/li><li><strong>Onde:<\/strong> virtual<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Shoptalk Fall Meetup&nbsp;<\/strong><\/h4>\n\n\n\n<p>Por fim, o <a href=\"https:\/\/shoptalkfall.retailmeetup.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Shoptalk Fall Meetup<\/strong><\/a> \u00e9 uma maneira divertida e produtiva de se conectar virtualmente com a comunidade varejista em reuni\u00f5es e discuss\u00f5es interativas. Tudo isso em um ambiente amig\u00e1vel e aberto.<\/p>\n\n\n\n<ul><li><strong>Quando: <\/strong>2024<\/li><li><strong>Onde:<\/strong> virtual<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/nacao.digital\/fale-conosco\/?utm_source=blog&amp;utm_medium=post&amp;utm_content=banner-odv-ferramentas-para-ecommerce&amp;utm_campaign=eventos-de-e-commerce-e-marketing\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"750\" height=\"100\" src=\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2020\/04\/nacao-99-ferramentas-fino.jpg\" alt=\"99-ferramentas-para-e-commerces\" class=\"wp-image-5532\" srcset=\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2020\/04\/nacao-99-ferramentas-fino.jpg 750w, https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2020\/04\/nacao-99-ferramentas-fino-300x40.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>7. Traffic &amp; Conversion Summit<\/strong><\/h3>\n\n\n\n<p>O foco deste <a href=\"https:\/\/trafficandconversionsummit.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Traffic &amp; Conversion Summit<\/strong><\/a> \u00e9 o marketing digital, por\u00e9m com <em>insights <\/em>extremamente v\u00e1lidos para todas as pessoas que trabalham com e-commerce.\u00a0<\/p>\n\n\n\n<p>O evento prop\u00f5e tr\u00eas dias de imers\u00e3o com alguns dos maiores nomes do mercado para falar sobre as \u00faltimas <a href=\"https:\/\/nacao.digital\/blog\/10-ferramentas-de-marketing-extremamente-uteis-que-vao-economizar-seu-tempo\/\" target=\"_blank\" rel=\"noreferrer noopener\">ferramentas<\/a> e <a href=\"https:\/\/nacao.digital\/blog\/tendencias-de-marketing\/\" target=\"_blank\" rel=\"noreferrer noopener\">tend\u00eancias de marketing<\/a>, IA e t\u00e1ticas de efici\u00eancia, aquisi\u00e7\u00e3o e reten\u00e7\u00e3o de funcion\u00e1rios, at\u00e9 escalabilidade e muito mais.<\/p>\n\n\n\n<ul><li><strong>Quando: <\/strong>9 a 11 de junho de 2024<\/li><li><strong>Onde:<\/strong> Las Vegas<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>8. Retail Week Live<\/strong><\/h3>\n\n\n\n<p>Com mais de 300 empresas participantes e 200 palestrantes, a <a href=\"https:\/\/live.retail-week.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Retail Week Live<\/a> \u00e9 um dos principais eventos de varejo na Inglaterra. Com novidades e \u00f3timas oportunidades de networking tanto para o offline quanto para o online, o evento \u00e9 imperd\u00edvel para quem est\u00e1 na \u00e1rea durante seu acontecimento.<\/p>\n\n\n\n<ul><li><strong>Quando: <\/strong>2024<\/li><li><strong>Onde:<\/strong> Londres<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2018\/05\/eventos-de-ecommerce-2.png\" alt=\"Imagem de pessoas assistindo uma palestra e batendo palmas.\" class=\"wp-image-8049\" width=\"600\" srcset=\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2018\/05\/eventos-de-ecommerce-2.png 1000w, https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2018\/05\/eventos-de-ecommerce-2-300x200.png 300w, https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2018\/05\/eventos-de-ecommerce-2-768x512.png 768w, https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2018\/05\/eventos-de-ecommerce-2-150x100.png 150w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption>Retail Week Live acontece em Londres. Foto: Reprodu\u00e7\u00e3o\/Retail Week Live.<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>9. Internet Retailing Expo<\/strong><\/h3>\n\n\n\n<p>Um dos eventos de e-commerce mais esperados do ano, o <a href=\"https:\/\/internetretailingexpo.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Internet Retailing Expo<\/strong><\/a><strong> <\/strong>re\u00fane mais de 5 mil visitantes em suas edi\u00e7\u00f5es. Com grandes nomes do varejo digital, como diretores da Amazon, traz muitos <em>insights <\/em>e novas oportunidades para profissionais de todo o mundo.<\/p>\n\n\n\n<ul><li><strong>Quando: <\/strong>24 e 25 de maio de 2023<\/li><li><strong>Onde:<\/strong> Birmingham, na Inglaterra<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>10. Retail Global<\/strong><\/h3>\n\n\n\n<p>O <a href=\"https:\/\/www.retailglobal.com.au\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Retail Global<\/strong><\/a> envolve tr\u00eas dias de imers\u00e3o no universo do e-commerce, com aprendizados ricos e <em>networking<\/em> fant\u00e1stico.\u00a0<\/p>\n\n\n\n<ul><li><strong>Quando: <\/strong>2024<\/li><li><strong>Onde:<\/strong> Gold Coast, Austr\u00e1lia<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>11. IRCE (Chicago, EUA)<\/strong><\/h3>\n\n\n\n<p>A <a href=\"https:\/\/retailinnovationconference.com\/irce\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Internet Retailer Conference + Exhibition<\/strong><\/a>, conhecida tamb\u00e9m como apenas IRCE, \u00e9 um dos maiores eventos de e-commerce de todo o mundo. Com <em>insights <\/em>importantes para lojas virtuais de diversos tamanhos, a edi\u00e7\u00e3o de 2018 contou com mais de 10 mil participantes.<\/p>\n\n\n\n<ul><li><strong>Quando: <\/strong>13 a 15 de junho 2023<\/li><li><strong>Onde:<\/strong> McCormick Place, Chicago<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>12. Inbound<\/strong><\/h3>\n\n\n\n<p>O <a href=\"https:\/\/www.inbound.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Inbound<\/strong><\/a> \u00e9 organizado pela HubSpot e reconhecido por, desde 2012, reunir os melhores profissionais de marketing do mundo. Em 2020 e 2021, em raz\u00e3o da <a href=\"https:\/\/nacao.digital\/blog\/melhorar-a-experiencia-do-cliente\/\" target=\"_blank\" rel=\"noreferrer noopener\">pandemia<\/a>, as edi\u00e7\u00f5es presenciais foram substitu\u00eddas por eventos online.<\/p>\n\n\n\n<p>Em 2022, os organizadores prepararam o primeiro <a href=\"https:\/\/nacao.digital\/blog\/livros-sobre-inbound-marketing\/\" target=\"_blank\" rel=\"noreferrer noopener\">Inbound<\/a> h\u00edbrido (presencial, em Boston, e online), que foi realizado em setembro, e voc\u00ea pode <a href=\"https:\/\/join.inbound.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>acessar a biblioteca de conte\u00fado<\/strong><\/a> para conferir tudo que rolou na \u00faltima edi\u00e7\u00e3o.<\/p>\n\n\n\n<p>A programa\u00e7\u00e3o de 2023 ainda n\u00e3o est\u00e1 definida, mas s\u00f3 d\u00e1 para esperar grandes nomes de um evento que j\u00e1 recebeu palestrantes como Michelle Obama, Issa Rae e Gary Vaynerchuk, al\u00e9m de sess\u00f5es lideradas por profissionais de marketing e vendas.<\/p>\n\n\n\n<ul><li><strong>Quando:<\/strong> 5 a 8 de setembro de 2023<\/li><li><strong>Onde: <\/strong>Boston (EUA) e online<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Eventos de e-commerce e marketing nacionais<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>13. Eventos do E-commerce Brasil&nbsp;<\/strong><\/h3>\n\n\n\n<p>O <a href=\"https:\/\/www.ecommercebrasil.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>E-commerce Brasil<\/strong><\/a><strong> <\/strong>\u00e9 um portal essencial para quem busca not\u00edcias sobre marketplaces e lojas virtuais. S\u00e3o mais de 2,5 mil textos publicados por ano sobre o panorama do com\u00e9rcio eletr\u00f4nico no Brasil, com uma audi\u00eancia entre 600 e 700 mil acessos mensais, sendo o maior portal de not\u00edcias da Am\u00e9rica Latina no segmento de <a href=\"https:\/\/nacao.digital\/blog\/plataforma-de-e-commerce\/\" target=\"_blank\" rel=\"noreferrer noopener\">e-commerce<\/a>.<\/p>\n\n\n\n<p>Ou seja, no portal E-Commerce Brasil voc\u00ea tem informa\u00e7\u00f5es confi\u00e1veis e de \u00faltima hora para uma performance muito mais ligada \u00e0s necessidades dos seus clientes.<\/p>\n\n\n\n<p>Al\u00e9m disso, o site, que atua desde 2011 com produ\u00e7\u00e3o di\u00e1ria e especializada de artigos t\u00e9cnicos e not\u00edcias com temas relevantes para o com\u00e9rcio eletr\u00f4nico no Brasil, oferece cursos e <em>workshops<\/em>, mas tamb\u00e9m realiza os principais eventos de neg\u00f3cios do setor de e-commerce do pa\u00eds.<\/p>\n\n\n\n<p>Portanto, al\u00e9m de encontrar novidades sobre neg\u00f3cios, startups, plataformas online, canais de distribui\u00e7\u00e3o, vendas e log\u00edstica, redes sociais, <a href=\"https:\/\/nacao.digital\/blog\/como-escolher-gateway-de-pagamento\/\" target=\"_blank\" rel=\"noreferrer noopener\">meios de pagamento<\/a> e muito mais, voc\u00ea pode aprender presencialmente ou online com os maiores nomes do setor.<\/p>\n\n\n\n<p>A cada ano, novos eventos surgem. Em 2023, oito encontros est\u00e3o programados, entre f\u00f3runs, confer\u00eancias e congressos.<\/p>\n\n\n\n<p>Destaque para o <a href=\"https:\/\/eventos.ecommercebrasil.com.br\/forum\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>F\u00f3rum E-commerce Brasil 2023<\/strong><\/a>, que chega a sua 14\u00aa edi\u00e7\u00e3o e acontece nos dias 25, 26 e 27 de julho de 2023. O encontro<strong> <\/strong>sempre traz palestrantes nacionais e internacionais que s\u00e3o refer\u00eancias em suas \u00e1reas para conversar com o p\u00fablico e trocar experi\u00eancias sobre neg\u00f3cios digitais.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"wpex-responsive-media\"><iframe title=\"F\u00f3rum E-Commerce Brasil &#039;22 - Como foi o evento\" width=\"980\" height=\"551\" src=\"https:\/\/www.youtube.com\/embed\/Jwq1QyJ_iUA?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/span>\n<\/div><\/figure>\n\n\n\n<p>Em 2022, foram 15.000 congressistas, mais de 20 \u00e1reas de conte\u00fado, mais de 220 expositores e mais de 200 palestrantes como Andr\u00e9 Sabioni, Head of Industry Meta (Facebook); Manuela Cardona, Diretora de Desenvolvimento de Mercado da Panvel Farm\u00e1cias; Konrad Dantas CEO e Creator do Kondzilla; Anadege Freitas, Director of Content and Partnerships da Twitch, entre tantos outros.<\/p>\n\n\n\n<p>Os outros eventos programados s\u00e3o:<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Confer\u00eancia E-commerce Brasil 2023 \u2014 Sa\u00fade &amp; Farma\u00a0<\/strong><\/h4>\n\n\n\n<p>Evento de marketing em S\u00e3o Paulo destinado a reunir os principais l\u00edderes do mercado de <a href=\"https:\/\/nacao.digital\/blog\/eqi-saude-higiene-beleza\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sa\u00fade<\/a> &amp; Farma para abordar tem\u00e1ticas como e-commerce, marketplaces, omnicanalidade e digitaliza\u00e7\u00e3o do setor.<\/p>\n\n\n\n<p>No total, ser\u00e3o quatro palestras: Resultados do e-commerce em 2022 e tend\u00eancias para 2023; Pinterest: o lugar da positividade e das tend\u00eancias de bem-estar; Como surfar tend\u00eancias e gerar resultados em 2023; Tend\u00eancias e comportamento de consumo com foco em sa\u00fade e bem-estar.<\/p>\n\n\n\n<ul><li><strong>Quando:<\/strong> 12 de abril<\/li><li><strong>Onde: <\/strong>S\u00e3o Paulo\u00a0<\/li><li><strong>Mais informa\u00e7\u00f5es em: <\/strong><a href=\"https:\/\/eventos.ecommercebrasil.com.br\/conferencia-saude-farma\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/eventos.ecommercebrasil.com.br\/conferencia-saude-farma\/<\/a>\u00a0<\/li><\/ul>\n\n\n\n<p>Alguns outros eventos do E-commerce Brasil ainda n\u00e3o possuem program\u00e7\u00e3o definida, mas a data j\u00e1 est\u00e1 estabelecida. S\u00e3o eles:<\/p>\n\n\n\n<ul><li><a href=\"https:\/\/eventos.ecommercebrasil.com.br\/forum-industria-digital\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>F\u00f3rum Ind\u00fastria Digital 2023<\/strong><\/a><strong>: <\/strong>17 de maio, em S\u00e3o Paulo\u00a0<\/li><li><a href=\"https:\/\/eventos.ecommercebrasil.com.br\/conferencia-beauty\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Confer\u00eancia E-commerce Brasil 2023 \u2014 Encontro de L\u00edderes (Beauty)<\/strong><\/a><strong>: <\/strong>13 de setembro, em S\u00e3o Paulo<\/li><li><a href=\"https:\/\/eventos.ecommercebrasil.com.br\/congresso-digitalizacao-lojas-fisicas\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Congresso Digitaliza\u00e7\u00e3o de Lojas F\u00edsicas 2023<\/strong><\/a><strong>: <\/strong>30 de outubro, em S\u00e3o Paulo<\/li><li><a href=\"https:\/\/eventos.ecommercebrasil.com.br\/congresso-rio-grande-do-sul\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Congresso E-commerce Brasil RS 2023<\/strong><\/a><strong>:<\/strong> 14 de novembro, no Rio Grande do Sul<\/li><\/ul>\n\n\n\n<p>O segredo \u00e9 ficar de olho na <a href=\"https:\/\/eventos.ecommercebrasil.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>p\u00e1gina oficial de eventos do E-commerce Brasil<\/strong><\/a> para acompanhar mais detalhes sobre toda a programa\u00e7\u00e3o de f\u00f3runs e encontros previstos para 2023\/2024.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>14. Gramado Summit<\/strong><\/h3>\n\n\n\n<p>A <a href=\"https:\/\/www.gramadosummit.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Gramado Summit<\/strong><\/a> \u00e9 voltada para os temas de <a href=\"https:\/\/nacao.digital\/blog\/comunicacao-entre-empresa\/\" target=\"_blank\" rel=\"noreferrer noopener\">comunica\u00e7\u00e3o<\/a>, marketing e <a href=\"https:\/\/nacao.digital\/blog\/quanto-vale-sua-empresa\/\" target=\"_blank\" rel=\"noreferrer noopener\">finan\u00e7as<\/a>. A edi\u00e7\u00e3o 2023 contar\u00e1 com mais de 200 palestrantes, que v\u00e3o proporcionar uma verdadeira imers\u00e3o no ecossistema de inova\u00e7\u00e3o.<\/p>\n\n\n\n<p>O line-up de palestrantes confirmados at\u00e9 agora est\u00e1 assim: Edu Lyra, CEO e fundador da ONG Gerando Falc\u00f5es, que viabiliza projetos de impacto social em periferias e favelas do Brasil; Helena Bertho, diretora global de diversidade e inclus\u00e3o da Nubank; Danni Suzuki, atriz, diretora e apresentadora de televis\u00e3o brasileira; Bruna Cutrupi, l\u00edder de solu\u00e7\u00f5es estrat\u00e9gicas da Johnson &amp; Johnson Medtech, entre outros.<\/p>\n\n\n\n<ul><li><strong>Quando:<\/strong> 12 a 14 de abril de 2023<\/li><li><strong>Onde: <\/strong>Gramado (RS)<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>15. Vtex Day<\/strong><\/h3>\n\n\n\n<p>Com o lema de \u201co dia de fazer acontencer\u201d, o <a href=\"https:\/\/vtexday.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Vtex Day 2023<\/strong><\/a> est\u00e1 marcado para o segundo semestre, ser\u00e1 100% presencial e conta com tr\u00eas possibilidades de ingressos: VIP, full-pass e pacote full-pass.\u00a0<\/p>\n\n\n\n<p>O evento est\u00e1 entre os maiores encontros de neg\u00f3cios digitais do mundo e \u00e9 reconhecido pelo conte\u00fado e pelos cases que apresentam um panorama do mercado.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"wpex-responsive-media\"><iframe title=\"VTEX DAY 2022\" width=\"980\" height=\"551\" src=\"https:\/\/www.youtube.com\/embed\/8pzZiWSyyAA?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/span>\n<\/div><\/figure>\n\n\n\n<p>As palestras do VTEX DAY acontecer\u00e3o em 8 palcos, cada um deles com uma programa\u00e7\u00e3o espec\u00edfica.&nbsp; As apresenta\u00e7\u00f5es ter\u00e3o dura\u00e7\u00e3o m\u00e9dia&nbsp; de 30 a 35 minutos. Haver\u00e1 um intervalo&nbsp; de 10 minutos entre cada uma delas. E os ingressos s\u00e3o limitados!<\/p>\n\n\n\n<ul><li><strong>Quando:<\/strong> 5 e 6 de junho de 2023<\/li><li><strong>Onde:<\/strong> S\u00e3o Paulo Expo, em S\u00e3o Paulo<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>16. Digitalks Expo 2023<\/strong><\/h3>\n\n\n\n<p>Evento sobre dados e tend\u00eancias tecnol\u00f3gicas promovido pela Digitalks. A \u00faltima edi\u00e7\u00e3o, em 2022, reuniu mais de 8.000 mil pessoas e reiterou a import\u00e2ncia dos eventos presenciais para a gera\u00e7\u00e3o de neg\u00f3cios, considerando o p\u00f3s-pandemia.&nbsp;<\/p>\n\n\n\n<p>Em 2023, o evento <a href=\"https:\/\/digitalks.com.br\/expo\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Digitalks Expo<\/strong><\/a> acontece na S\u00e3o Paulo Expo. Ser\u00e3o 2 dias de evento, audit\u00f3rios com muito conte\u00fado, \u00e1rea de <a href=\"https:\/\/nacao.digital\/blog\/como-utilizar-o-igtv-em-negocios\/\" target=\"_blank\" rel=\"noreferrer noopener\">neg\u00f3cios<\/a> com as principais empresas do setor e a presen\u00e7a dos formadores de opini\u00e3o mais relevantes do momento para compartilhar tend\u00eancias do mercado nacional e internacional.<\/p>\n\n\n\n<p>Entre as palestras de destaques que j\u00e1 foram realizadas no evento est\u00e3o as da Microsoft, Aliexpress, Adobe, Rappi Brasil, Creditas Benef\u00edcios, Taboola, Olist, Banco do Brasil e Ita\u00fa BBA.<\/p>\n\n\n\n<ul><li><strong>Quando: <\/strong>23 e 24 de agosto de 2023<\/li><li><strong>Onde:<\/strong> S\u00e3o Paulo (SP)<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>17. Fire Festival<\/strong><\/h3>\n\n\n\n<p>Voltado para comunicadores, desenvolvedores, empres\u00e1rios e startups, o <a href=\"https:\/\/firefestival.hotmart.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Fire Festival<\/strong><\/a> \u00e9 um evento global, pois desde 2015 re\u00fane palestrantes do mundo todo. De l\u00e1 para c\u00e1, j\u00e1 ocorreram mais de 400 palestras in\u00e9ditas e mais de 55 mil participantes marcaram presen\u00e7a! Para quem quer aprender e discutir sobre o futuro do mercado digital, \u00e9 um prato cheio.\u00a0<\/p>\n\n\n\n<p>Para 2023, ser\u00e3o tr\u00eas dias de atividades e palestras sobre conte\u00fado, tecnologia, empreendedorismo e educa\u00e7\u00e3o. Alguns dos nomes j\u00e1 confirmados s\u00e3o: Leandro Ladeira \u2014 CMO da We do Care; Bettina Rudolph \u2014 Fundadora da BR Marketing;<\/p>\n\n\n\n<p>Tathiane De\u00e2ndhela \u2014 Fundadora e CEO do Instituto De\u00e2ndhela; e Hyeser de Souza \u2014 Especialista em Redes Sociais HS Publicidade Digital.<\/p>\n\n\n\n<ul><li><strong>Quando:<\/strong> 24, 25 e 26 de agosto de 2023<\/li><li><strong>Onde: <\/strong>Expominas, em Belo Horizonte (MG)<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/nacao.digital\/fale-conosco\/?utm_source=blog&amp;utm_medium=post&amp;utm_content=banner-odv-calendario-2023&amp;utm_campaign=eventos-de-e-commerce-e-marketing\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"700\" height=\"100\" src=\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2017\/12\/CTA-700x100px.jpg\" alt=\"baixar gratuitamente calend\u00e1rio 2023 para e-commerce\" class=\"wp-image-7752\" srcset=\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2017\/12\/CTA-700x100px.jpg 700w, https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2017\/12\/CTA-700x100px-300x43.jpg 300w, https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2017\/12\/CTA-700x100px-150x21.jpg 150w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>18. SaaStr<\/strong><\/h3>\n\n\n\n<p>A maior confer\u00eancia de SaaS do mundo ter\u00e1 formato presencial. Na \u00faltima edi\u00e7\u00e3o, em 2022, o <a href=\"https:\/\/www.saastrannual2023.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>SaaStr<\/strong><\/a> ocorreu em tr\u00eas dias do m\u00eas de setembro, com mais de 250 palestrantes, 100 workshops e 1 mil sess\u00f5es de mentoria; tudo para ajudar os empreendedores a escalar rapidamente seus neg\u00f3cios.\u00a0<\/p>\n\n\n\n<p>Em 2023, a ideia \u00e9 trazer 300 palestrantes de empresas SaaS mundiais, proporcionar mais de 2 mil sess\u00f5es de networking e muito mais.<\/p>\n\n\n\n<ul><li><strong>Quando:<\/strong> 6 a 8 de setembro de 2023<\/li><li><strong>Onde: <\/strong>S\u00e3o Francisco (EUA)<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>19. <\/strong><strong>SEO Summit <\/strong><strong>2023<\/strong><\/h3>\n\n\n\n<p>Evento 100% online e gratuito com os maiores especialistas em <a href=\"https:\/\/nacao.digital\/blog\/seo-para-youtube\/\" target=\"_blank\" rel=\"noreferrer noopener\">SEO<\/a>, t\u00e9cnica de ranqueamento org\u00e2nico nos motores de busca e important\u00edssima para qualquer e-commerce ou <a href=\"https:\/\/nacao.digital\/blog\/marketing-personalizado\/\" target=\"_blank\" rel=\"noreferrer noopener\">marca<\/a>. Mais de 20 mil participantes j\u00e1 foram registrados!<\/p>\n\n\n\n<p>Realizado pela Conversion, o <a href=\"https:\/\/www.seosummit.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>SEO Summit 2023<\/strong><\/a> ainda n\u00e3o tem a programa\u00e7\u00e3o completa definida, mas as inscri\u00e7\u00f5es est\u00e3o abertas.<\/p>\n\n\n\n<ul><li><strong>Quando:<\/strong> 28 e 29 de setembro de 2023<\/li><li><strong>Onde: <\/strong>S\u00e3o Paulo e online<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/nacao.digital\/fale-conosco\/?utm_source=blog&amp;utm_medium=post&amp;utm_content=banner-odv-perfomance-content&amp;utm_campaign=eventos-de-e-commerce-e-marketing\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"700\" height=\"100\" src=\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2021\/11\/performance-content-descricao-de-produto-nacao-digital.jpg\" alt=\"performance-content-descricao-de-produto-nacao-digital\" class=\"wp-image-6855\" srcset=\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2021\/11\/performance-content-descricao-de-produto-nacao-digital.jpg 700w, https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2021\/11\/performance-content-descricao-de-produto-nacao-digital-300x43.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>20. Maxim\u00eddia<\/strong><\/h3>\n\n\n\n<p>O <a href=\"https:\/\/www.meioemensagem.com.br\/maximidia\/evento\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Maxim\u00eddia<\/strong><\/a> \u00e9 um evento realizado pelo Meio &amp; Mensagem, ve\u00edculo especializado na cobertura do mercado publicit\u00e1rio, e prop\u00f5e debater estrat\u00e9gias e inova\u00e7\u00e3o para anunciantes, ag\u00eancias e empresas de comunica\u00e7\u00e3o.\u00a0<\/p>\n\n\n\n<p>Em 2022, o Maxim\u00eddia foi h\u00edbrido. No per\u00edodo da manh\u00e3, 100% dos conte\u00fados foram realizados online, com trilhas que abordaram criatividade, diversidade, entre outros. \u00c0 tarde, o encontro foi presencial, tornando-se um grande campo para networking. A programa\u00e7\u00e3o vespertina come\u00e7ou com bate-papos com CEOs de grandes empresas, seguida por pain\u00e9is focados em neg\u00f3cios, economia, tecnologia, inova\u00e7\u00e3o, sociedade e marcas.&nbsp;<\/p>\n\n\n\n<p>O patroc\u00ednio master \u00e9 de grandes nomes do mercado como Globo, UOL, Neooh e Warner Bros. Discovery.&nbsp;<\/p>\n\n\n\n<p>A programa\u00e7\u00e3o de 2023 ainda n\u00e3o foi definida, mas a data e o local, sim!<\/p>\n\n\n\n<ul><li><strong>Quando:<\/strong> 3 a 5 de outubro de 2023<\/li><li><strong>Onde: <\/strong>S\u00e3o Paulo<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>21. <\/strong><strong>RD Summit 2023<\/strong><\/h3>\n\n\n\n<p>Sem d\u00favidas, o <a href=\"https:\/\/www.rdsummit.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>RD Summit<\/strong><\/a> \u00e9 um dos eventos de marketing mais populares do Brasil. Ou melhor, como o pr\u00f3prio slogan diz, \u00e9 \u201cmais do que um evento, um festival\u201d.<\/p>\n\n\n\n<p>A primeira edi\u00e7\u00e3o foi em 2013, com 600 participantes. A cada ano, o evento aumentava de tamanho, tanto em visitantes quanto em atra\u00e7\u00f5es. Desde 2018, quando o RD Summit cresceu ainda mais, passou a ser realizado em tr\u00eas dias, agregando novas experi\u00eancias para o p\u00fablico.<\/p>\n\n\n\n<p>E para 2023, traz uma grande novidade: ao inv\u00e9s de Florian\u00f3polis (SC), como grande parte das edi\u00e7\u00f5es anteriores, ser\u00e1 realizado em S\u00e3o Paulo (SP).&nbsp;<\/p>\n\n\n\n<p>Os tr\u00eas dias de palestras, intera\u00e7\u00f5es, surpresas e networking s\u00e3o focados em conte\u00fado, conex\u00e3o e entretenimento \u2014 n\u00e3o por acaso, rolam shows musicais e at\u00e9 um festival gastron\u00f4mico com <em>food trucks.<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"600\" height=\"378\" src=\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2018\/05\/eventos-de-ecommerce-e-marketing.jpg\" alt=\"eventos-de-ecommerce-e-marketing\" class=\"wp-image-5059\" srcset=\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2018\/05\/eventos-de-ecommerce-e-marketing.jpg 600w, https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2018\/05\/eventos-de-ecommerce-e-marketing-300x189.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption>\u00daltima edi\u00e7\u00e3o presencial do RD Summit, o maior evento de marketing digital do Brasil, foi em 2019.<\/figcaption><\/figure><\/div>\n\n\n\n<ul><li><strong>Quando:<\/strong> 8 a 10 de novembro de 2023<\/li><li><strong>Onde:<\/strong> Expo Center Norte, em S\u00e3o Paulo (SP)<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>22. <\/strong><strong>Mercado Livre Experience<\/strong><\/h3>\n\n\n\n<p>A edi\u00e7\u00e3o de 2022 da MELIXP reuniu 12 mil empreendedores, mais de 80 palestrantes, mais de 70 parceiros e marcas do renomado <a href=\"https:\/\/nacao.digital\/blog\/ecommerce-ou-marketplace\/\" target=\"_blank\" rel=\"noreferrer noopener\">marketplace<\/a>, al\u00e9m de proporcionar quatro arenas de conte\u00fado.<\/p>\n\n\n\n<p>Entre os nomes que marcaram a \u00faltima edi\u00e7\u00e3o, est\u00e3o Gabriela Szprinc \u2014&nbsp; Diretora S\u00eanior Pagamentos do Mercado Pago; Bruna Ortega \u2014 Diretora de Contas da WGSN; Caio Rinaldi \u2014 Diretor de Varejo da Disney e muitos outros.<\/p>\n\n\n\n<p>A divis\u00e3o do evento se deu em quatro palcos: #Voc\u00eaVendeu, que abordava temas relacionados \u00e0 \u201ccomo vender no Mercado Livre?\u201d; #Voc\u00eaCresceu, com dicas sobre como escalar um neg\u00f3cio; #Voc\u00eaVenceu que trabalhava sugest\u00f5es para diferenciar a empresa; e #Voc\u00eaTransforma, olhando para o futuro do neg\u00f3cio. Ao final do evento, os participantes presenciaram um show musical.<\/p>\n\n\n\n<p>A edi\u00e7\u00e3o 2023 ainda n\u00e3o foi confirmada, mas \u00e9 bom ficar de olho no <a href=\"https:\/\/www.melixp.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">site oficial do evento<\/a> e n\u00e3o perder nenhuma novidade futura.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>23. Feira Brasileira do Varejo<\/strong><\/h3>\n\n\n\n<p>Um dos maiores eventos de varejo do pa\u00eds, a<strong> <\/strong><a href=\"https:\/\/feirabrasileiradovarejo.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Feira Brasileira de Varejo<\/strong><\/a> acontece em Porto Alegre. Com grandes nomes do mercado nacional, \u00e9 interessante tanto para quem atua no e-commerce ou no offline.<\/p>\n\n\n\n<ul><li><strong>Quando:<\/strong> 24, 25 e 26 de maio de 2023<\/li><li><strong>Onde:<\/strong> Centro de Eventos FIERGS, Porto Alegre (RS)<\/li><\/ul>\n\n\n\n<p>Que tal tamb\u00e9m ficar por dentro das datas mais importantes de 2023 para o com\u00e9rcio eletr\u00f4nico? Baixe o <a href=\"https:\/\/conteudo.anymarket.com.br\/calendario-ecommerce-2022\/?utm_source=blog&amp;utm_medium=post&amp;utm_content=calendario-2022&amp;utm_campaign=eventos-de-e-commerce\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Calend\u00e1rio de E-commerce 2022<\/strong><\/a> produzido pela Na\u00e7\u00e3o Digital e incorpore-o \u00e0 sua agenda e boas vendas!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/nacao.digital\/fale-conosco\/?utm_source=blog&amp;utm_medium=post&amp;utm_content=cta-odv-calendario-2023&amp;utm_campaign=eventos-de-e-commerce-e-marketing\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"700\" height=\"200\" src=\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2017\/12\/CTA-700x200px.jpg\" alt=\"calend\u00e1rio para e-commerce 2023\" class=\"wp-image-7750\" srcset=\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2017\/12\/CTA-700x200px.jpg 700w, https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2017\/12\/CTA-700x200px-300x86.jpg 300w, https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2017\/12\/CTA-700x200px-150x43.jpg 150w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este conte\u00fado foi atualizado em: 23\/06\/2026 Participar de eventos de e-commerce e marketing digital \u00e9 uma excelente forma de descobrir tend\u00eancias, ideias inovadoras e detalhes de estrat\u00e9gias bem sucedidas. Al\u00e9m de serem inspiradores e, muitas vezes, decisivos para mudan\u00e7as na gest\u00e3o e nos processos de trabalho, s\u00e3o boas oportunidades para fazer neg\u00f3cios \u2014 o famigerado&hellip;<\/p>\n","protected":false},"author":7,"featured_media":5623,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_focuskw":"eventos de e-commerce","_yoast_wpseo_title":"23 eventos de e-commerce e marketing para 2023\/24","_yoast_wpseo_metadesc":"Veja a agenda dos mais importantes eventos de e-commerce e marketing de 2023\/2024, e aprofunde seus conhecimentos!","footnotes":""},"categories":[113,312],"tags":[479,95,184,423,477,96,97,478],"post_series":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>23 eventos de e-commerce e marketing para 2023\/24<\/title>\n<meta name=\"description\" content=\"Veja a agenda dos mais importantes eventos de e-commerce e marketing de 2023\/2024, e aprofunde seus conhecimentos!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"23 eventos de e-commerce e marketing para 2023\/24\" \/>\n<meta property=\"og:description\" content=\"Veja a agenda dos mais importantes eventos de e-commerce e marketing de 2023\/2024, e aprofunde seus conhecimentos!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da Na\u00e7\u00e3o Digital\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/inbound.commerce\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-23T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-23T15:16:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2018\/05\/eventos-de-ecommerce-e-marketing-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o - Na\u00e7\u00e3o Digital\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o - Na\u00e7\u00e3o Digital\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o - Na\u00e7\u00e3o Digital\",\"@id\":\"https:\/\/nacao.digital\/blog\/#\/schema\/person\/4e45d0f5b6d52948e113abab0619dcdc\"},\"headline\":\"23 eventos de e-commerce e marketing para 2023\/24\",\"datePublished\":\"2023-03-23T10:00:00+00:00\",\"dateModified\":\"2026-06-23T15:16:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/\"},\"wordCount\":3440,\"commentCount\":9,\"publisher\":{\"@id\":\"https:\/\/nacao.digital\/blog\/#organization\"},\"keywords\":[\"digitalks\",\"eventos de e-commerce\",\"eventos de e-commerce e marketing\",\"eventos online\",\"fire festival\",\"f\u00f3rum e-commerce brasil\",\"rd summit\",\"vtex day\"],\"articleSection\":[\"E-commerce\",\"Marketing\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/\",\"url\":\"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/\",\"name\":\"23 eventos de e-commerce e marketing para 2023\/24\",\"isPartOf\":{\"@id\":\"https:\/\/nacao.digital\/blog\/#website\"},\"datePublished\":\"2023-03-23T10:00:00+00:00\",\"dateModified\":\"2026-06-23T15:16:01+00:00\",\"description\":\"Veja a agenda dos mais importantes eventos de e-commerce e marketing de 2023\/2024, e aprofunde seus conhecimentos!\",\"breadcrumb\":{\"@id\":\"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/nacao.digital\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"23 eventos de e-commerce e marketing para 2023\/24\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nacao.digital\/blog\/#website\",\"url\":\"https:\/\/nacao.digital\/blog\/\",\"name\":\"Blog da Na\u00e7\u00e3o Digital\",\"description\":\"Aprenda as melhores estrat\u00e9gias para atrair p\u00fablico mais segmentado, converter mais e vender muito. Tudo isso usando a metodologia de Inbound Marketing para E-commerce.\",\"publisher\":{\"@id\":\"https:\/\/nacao.digital\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nacao.digital\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nacao.digital\/blog\/#organization\",\"name\":\"Na\u00e7\u00e3o Digital\",\"url\":\"https:\/\/nacao.digital\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nacao.digital\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2018\/05\/nacao-digital.jpg\",\"contentUrl\":\"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2018\/05\/nacao-digital.jpg\",\"width\":590,\"height\":389,\"caption\":\"Na\u00e7\u00e3o Digital\"},\"image\":{\"@id\":\"https:\/\/nacao.digital\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/inbound.commerce\",\"https:\/\/www.instagram.com\/nacaodigital\/\",\"https:\/\/pt.linkedin.com\/company\/na\u00e7\u00e3o-digital\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nacao.digital\/blog\/#\/schema\/person\/4e45d0f5b6d52948e113abab0619dcdc\",\"name\":\"Reda\u00e7\u00e3o - Na\u00e7\u00e3o Digital\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nacao.digital\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/02e4691d00230d3425c562e7e363f571?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/02e4691d00230d3425c562e7e363f571?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o - Na\u00e7\u00e3o Digital\"},\"description\":\"Equipe de Reda\u00e7\u00e3o da Na\u00e7\u00e3o Digital\",\"sameAs\":[\"http:\/\/nacao.digital\"],\"url\":\"https:\/\/nacao.digital\/blog\/author\/redacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"23 eventos de e-commerce e marketing para 2023\/24","description":"Veja a agenda dos mais importantes eventos de e-commerce e marketing de 2023\/2024, e aprofunde seus conhecimentos!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/","og_locale":"pt_BR","og_type":"article","og_title":"23 eventos de e-commerce e marketing para 2023\/24","og_description":"Veja a agenda dos mais importantes eventos de e-commerce e marketing de 2023\/2024, e aprofunde seus conhecimentos!","og_url":"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/","og_site_name":"Blog da Na\u00e7\u00e3o Digital","article_publisher":"https:\/\/www.facebook.com\/inbound.commerce","article_published_time":"2023-03-23T10:00:00+00:00","article_modified_time":"2026-06-23T15:16:01+00:00","og_image":[{"width":1500,"height":800,"url":"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2018\/05\/eventos-de-ecommerce-e-marketing-1.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o - Na\u00e7\u00e3o Digital","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o - Na\u00e7\u00e3o Digital","Est. tempo de leitura":"20 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/#article","isPartOf":{"@id":"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/"},"author":{"name":"Reda\u00e7\u00e3o - Na\u00e7\u00e3o Digital","@id":"https:\/\/nacao.digital\/blog\/#\/schema\/person\/4e45d0f5b6d52948e113abab0619dcdc"},"headline":"23 eventos de e-commerce e marketing para 2023\/24","datePublished":"2023-03-23T10:00:00+00:00","dateModified":"2026-06-23T15:16:01+00:00","mainEntityOfPage":{"@id":"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/"},"wordCount":3440,"commentCount":9,"publisher":{"@id":"https:\/\/nacao.digital\/blog\/#organization"},"keywords":["digitalks","eventos de e-commerce","eventos de e-commerce e marketing","eventos online","fire festival","f\u00f3rum e-commerce brasil","rd summit","vtex day"],"articleSection":["E-commerce","Marketing"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/","url":"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/","name":"23 eventos de e-commerce e marketing para 2023\/24","isPartOf":{"@id":"https:\/\/nacao.digital\/blog\/#website"},"datePublished":"2023-03-23T10:00:00+00:00","dateModified":"2026-06-23T15:16:01+00:00","description":"Veja a agenda dos mais importantes eventos de e-commerce e marketing de 2023\/2024, e aprofunde seus conhecimentos!","breadcrumb":{"@id":"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nacao.digital\/blog\/eventos-de-e-commerce-e-marketing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/nacao.digital\/blog\/"},{"@type":"ListItem","position":2,"name":"23 eventos de e-commerce e marketing para 2023\/24"}]},{"@type":"WebSite","@id":"https:\/\/nacao.digital\/blog\/#website","url":"https:\/\/nacao.digital\/blog\/","name":"Blog da Na\u00e7\u00e3o Digital","description":"Aprenda as melhores estrat\u00e9gias para atrair p\u00fablico mais segmentado, converter mais e vender muito. Tudo isso usando a metodologia de Inbound Marketing para E-commerce.","publisher":{"@id":"https:\/\/nacao.digital\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nacao.digital\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nacao.digital\/blog\/#organization","name":"Na\u00e7\u00e3o Digital","url":"https:\/\/nacao.digital\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nacao.digital\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2018\/05\/nacao-digital.jpg","contentUrl":"https:\/\/nacao.digital\/blog\/wp-content\/uploads\/2018\/05\/nacao-digital.jpg","width":590,"height":389,"caption":"Na\u00e7\u00e3o Digital"},"image":{"@id":"https:\/\/nacao.digital\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/inbound.commerce","https:\/\/www.instagram.com\/nacaodigital\/","https:\/\/pt.linkedin.com\/company\/na\u00e7\u00e3o-digital"]},{"@type":"Person","@id":"https:\/\/nacao.digital\/blog\/#\/schema\/person\/4e45d0f5b6d52948e113abab0619dcdc","name":"Reda\u00e7\u00e3o - Na\u00e7\u00e3o Digital","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nacao.digital\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/02e4691d00230d3425c562e7e363f571?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02e4691d00230d3425c562e7e363f571?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o - Na\u00e7\u00e3o Digital"},"description":"Equipe de Reda\u00e7\u00e3o da Na\u00e7\u00e3o Digital","sameAs":["http:\/\/nacao.digital"],"url":"https:\/\/nacao.digital\/blog\/author\/redacao\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nacao.digital\/blog\/wp-json\/wp\/v2\/posts\/1423"}],"collection":[{"href":"https:\/\/nacao.digital\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nacao.digital\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nacao.digital\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/nacao.digital\/blog\/wp-json\/wp\/v2\/comments?post=1423"}],"version-history":[{"count":14,"href":"https:\/\/nacao.digital\/blog\/wp-json\/wp\/v2\/posts\/1423\/revisions"}],"predecessor-version":[{"id":8535,"href":"https:\/\/nacao.digital\/blog\/wp-json\/wp\/v2\/posts\/1423\/revisions\/8535"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nacao.digital\/blog\/wp-json\/wp\/v2\/media\/5623"}],"wp:attachment":[{"href":"https:\/\/nacao.digital\/blog\/wp-json\/wp\/v2\/media?parent=1423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nacao.digital\/blog\/wp-json\/wp\/v2\/categories?post=1423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nacao.digital\/blog\/wp-json\/wp\/v2\/tags?post=1423"},{"taxonomy":"post_series","embeddable":true,"href":"https:\/\/nacao.digital\/blog\/wp-json\/wp\/v2\/post_series?post=1423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}